{"id":177,"date":"2012-06-13T22:46:31","date_gmt":"2012-06-13T22:46:31","guid":{"rendered":"https:\/\/aquileoparra.com\/pacho\/2012\/06\/13\/plan-mejoramiento\/"},"modified":"2012-06-13T22:46:31","modified_gmt":"2012-06-13T22:46:31","slug":"plan-mejoramiento","status":"publish","type":"post","link":"https:\/\/aquileoparra.com\/pacho\/2012\/06\/13\/plan-mejoramiento\/","title":{"rendered":"PLAN MEJORAMIENTO"},"content":{"rendered":"<p style=\"text-align: center;\"><em><strong><span style=\"font-size: 14pt; font-family: verdana,geneva; color: #333399;\">PLAN DE MEJORAMIENTO ACADEMICO 2012<\/span><\/strong><\/em><\/p>\n<p style=\"text-align: center;\"><span style=\"font-size: 14pt; font-family: verdana,geneva;\">\u00a0<\/span><\/p>\n<p style=\"text-align: center;\"><span style=\"font-size: 14pt; font-family: verdana,geneva;\"><em><strong><a href=\"mejoramiento1p\/mejoramiento1bimestre.htm\">Planes de mejoramiento 2011<\/a><\/strong><\/em>\u00a0 <em><strong><a href=\"index.php?option=com_remository&#038;Itemid=289&#038;func=select&#038;id=21\">Planes de mejoramiento 2012<\/a><\/strong><\/em> <br \/><\/span><\/p>\n<p style=\"text-align: center;\"><span style=\"font-size: 14pt; font-family: verdana,geneva;\"><\/span><\/p>\n<hr \/>\n<p>\u00a0<\/p>\n<p style=\"text-align: justify;\"><span style=\"font-size: 10pt; font-family: verdana,geneva;\"><em><strong>1.\u00a0\u00a0\u00a0 OBJETIVOS<\/strong><\/em><\/span><\/p>\n<p><span style=\"font-size: 10pt; font-family: verdana,geneva;\">Aplicar estrategias pedag\u00f3gicas que permitan el mejoramiento acad\u00e9mico\u00a0 de los estudiantes que presentan dificultades en las asignaturas y un bajo rendimiento acad\u00e9mico\u00a0 promediado el primero y segundo periodo de\u00a0 2012<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"font-size: 10pt; font-family: verdana,geneva;\">2.\u00a0\u00a0\u00a0 <em><strong>Objetivos espec\u00edficos.<\/strong><\/em><\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"font-size: 10pt; font-family: verdana,geneva;\">&#8211;\u00a0\u00a0\u00a0 Realizar un diagnostico\u00a0 estad\u00edstico\u00a0 de la mortalidad acad\u00e9mica\u00a0 del primero y segundo periodo.<\/span><br \/><span style=\"font-size: 10pt; font-family: verdana,geneva;\">&#8211;\u00a0\u00a0\u00a0 Analizar las principales causas desde el punto de vista de los estudiantes, padres de familia y docentes\u00a0 del bajo rendimiento escolar.<\/span><br \/><span style=\"font-size: 10pt; font-family: verdana,geneva;\">&#8211;\u00a0\u00a0\u00a0 Sensibilizar a los padres de familia\u00a0 sobre la importancia y deber de su acompa\u00f1amiento,\u00a0 supervisi\u00f3n y compromiso\u00a0\u00a0 con los deberes\u00a0 escolares de sus hijos.<\/span><br \/><span style=\"font-size: 10pt; font-family: verdana,geneva;\">&#8211;\u00a0\u00a0\u00a0 Aplicar estrategias de refuerzo y superaci\u00f3n de las debilidades presentadas por los estudiantes en las diferentes asignaturas.<\/span><br \/><span style=\"font-size: 10pt; font-family: verdana,geneva;\">&#8211;\u00a0\u00a0\u00a0 Dar cumplimiento a las normas vigentes estipuladas en el SIE, decreto 1290 y ley 115.<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"font-size: 10pt; font-family: verdana,geneva;\">\u00a0<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"font-size: 10pt; font-family: verdana,geneva;\">3.\u00a0<em><strong>\u00a0\u00a0 JUSTIFICACI\u00d3N.<\/strong><\/em><\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"font-size: 10pt; font-family: verdana,geneva;\">Teniendo en cuenta los resultados obtenidos en el primer periodo los cuales dan como resultado que una gran mayor\u00eda de estudiantes reprobaron m\u00e1s de tres asignaturas lo mismo que la preocupaci\u00f3n de los docentes por el desinter\u00e9s de los estudiantes por las actividades acad\u00e9micas, la falta de colaboraci\u00f3n de los padres de familia\u00a0 en el proceso educativo, la problem\u00e1tica familiar que presentan algunos estudiantes, las falencias que presentan los estudiantes por pocas base acad\u00e9micas de a\u00f1os anteriores, la indisciplina de algunos estudiantes que no permiten el normal desarrollo de las clases, la metodolog\u00eda utilizada por algunos docentes que seg\u00fan los estudiantes no motivan el aprendizaje entre\u00a0 otras problem\u00e1ticas, se evidencia la necesidad de de analizar y plantear\u00a0 y si es necesario replantear\u00a0 estrategias pedag\u00f3gicas que permitan superar\u00a0 las dificultades que se presentan hasta el momento, teniendo como base el compromiso de los padres de familia y estudiantes como factor principal para llevarlo a cabo.<\/span><\/p>\n<p style=\"text-align: center;\"><span style=\"font-size: 10pt; font-family: verdana,geneva;\">\u00a0<\/span><\/p>\n<p style=\"text-align: center;\"><span style=\"font-size: 10pt; font-family: verdana,geneva;\"><em><strong>4.\u00a0\u00a0\u00a0 PROCESOS Y ESTRATEGIAS DEL PLAN DE MEJORAMIENTO.<\/strong><\/em><\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"font-size: 10pt; font-family: verdana,geneva;\">_ Reunir a la comisi\u00f3n de evaluaci\u00f3n y promoci\u00f3n junto con los padres de familia\u00a0 de los estudiantes que presentan bajo rendimiento acad\u00e9mico <\/span><br \/><span style=\"font-size: 10pt; font-family: verdana,geneva;\">_ Realizar talleres con los padres de familia y estudiantes que permitan determinar las causas y soluciones desde la competencia y deberes de los padres de familia.<\/span><br \/><span style=\"font-size: 10pt; font-family: verdana,geneva;\">_ Realizar actividades pedag\u00f3gicas por parte de los docentes\u00a0 que permitan reforzar los temas\u00a0 que presentan dificultades\u00a0 en el primero y segundo periodo.<\/span><br \/><span style=\"font-size: 10pt; font-family: verdana,geneva;\">_ Aplicar evaluaciones por competencias de los temas que el estudiante\u00a0 deb\u00eda lograr en los dos periodos de acuerdo al plan de \u00e1rea y asignatura de la asignatura. \u201cevaluaciones en l\u00ednea tipo Icfes\u201d., Asignar trabajos\u00a0 te\u00f3ricos o pr\u00e1cticos\u00a0 que permitan aplicar y demostrar los temas tratados en el primer y segundo periodo.<\/span><br \/><span style=\"font-size: 10pt; font-family: verdana,geneva;\">_ Dise\u00f1ar un cronograma de evaluaciones, presentaci\u00f3n de trabajos y sustentaciones los cuales se iniciaran en la primera semana del tercer periodo.<\/span><br \/><span style=\"font-size: 10pt; font-family: verdana,geneva;\">_ Subir las respectivas notas de los periodos como recuperaci\u00f3n en el SIGES de tal manera que aparezcan reflejados en el tercer periodo.<\/span><br \/><span style=\"font-size: 10pt; font-family: verdana,geneva;\">_ Dar a conocer los criterios y formas de evaluaci\u00f3n y relacionar por medio de acta las notas obtenidas y\u00a0 lo mismo que estudiantes que no presentaron las actividades presentadas.<\/span><\/p>\n<p style=\"text-align: center;\"><em><strong>5.\u00a0\u00a0\u00a0 \u00a0CRONOGRAMA<\/strong><\/em><\/p>\n<p style=\"text-align: center;\"><em><strong> <\/p>\n<table border=\"0\">\n<tbody>\n<tr>\n<td>FECHA<\/td>\n<td>ACTIVIDAD<\/td>\n<td>RESPONSABLE<\/td>\n<\/tr>\n<tr>\n<td><span style=\"color: #0000ff;\">Junio 12 \u00a0\u00a0 Junio 15 \u00a0\u00a0 <br \/><\/span><\/td>\n<td>Dise\u00f1o<\/td>\n<td>Rector\u00eda y coordinaci\u00f3n acad\u00e9mica.<\/td>\n<\/tr>\n<tr>\n<td><span style=\"color: #0000ff;\">Junio 18 \u00a0\u00a0 Julio 22 <br \/><\/span><\/td>\n<td>Publicaci\u00f3n\u00a0\u00a0 en la Web\u00a0<\/td>\n<td>Coordinaci\u00f3n Acad\u00e9mica.<\/td>\n<\/tr>\n<tr>\n<td><span style=\"color: #0000ff;\">Julio 18 \u00a0\u00a0 Julio\u00a0 22<br \/><\/span><\/td>\n<td>Dise\u00f1o y publicaci\u00f3n de Actividades\u00a0 por asignatura por\u00a0 cada periodo<\/td>\n<td>Docentes de asignatura.<\/td>\n<\/tr>\n<tr>\n<td><span style=\"color: #0000ff;\">Julio 13 \u00a0\u00a0 Julio\u00a0 20\u00a0<\/span><\/td>\n<td>Elaboraci\u00f3n Estad\u00edstica acad\u00e9mica<\/td>\n<td>Coordinaci\u00f3n Acad\u00e9mica.<\/td>\n<\/tr>\n<tr>\n<td><span style=\"color: #0000ff;\">Julio 9 \u00a0\u00a0 Julio 25<\/span><\/td>\n<td>Aplicaci\u00f3n evaluaciones en l\u00ednea<\/td>\n<td>Coordinaci\u00f3n, Docentes, Estudiantes<\/td>\n<\/tr>\n<tr>\n<td><span style=\"color: #0000ff;\">Julio 23<\/span><\/td>\n<td>Informe\u00a0 estudiantes que debe presentar el plan de mejoramiento<\/td>\n<td>Docentes y Coordinaci\u00f3n acad\u00e9mica.<\/td>\n<\/tr>\n<tr>\n<td><span style=\"color: #0000ff;\">Julio 18<br \/><\/span><\/td>\n<td>Entrega Citaciones\u00a0 asistencia comit\u00e9 de evaluaci\u00f3n.<\/td>\n<td>Coordinaci\u00f3n y Directores de grupo.<\/td>\n<\/tr>\n<tr>\n<td><span style=\"color: #0000ff;\">Julio 23<br \/><\/span><\/td>\n<td><em><strong>Taller\u00a0 con padres de familia<\/strong><\/em><\/td>\n<td>Orientadora, Coordinador Acad\u00e9mico.<\/td>\n<\/tr>\n<tr>\n<td>\n<p>\u00a0<\/p>\n<p><em><strong><span style=\"color: #0000ff;\">Julio 23<br \/><\/span><\/strong><\/em><\/p>\n<\/td>\n<td>Reuni\u00f3n Consejo de evaluaci\u00f3n y promoci\u00f3n con padres de familia.<\/td>\n<td>\n<p>Consejo de evaluaci\u00f3n y promoci\u00f3n, docentes, padres<\/p>\n<p>de familia y estudiantes<\/p>\n<\/td>\n<\/tr>\n<tr>\n<td><span style=\"color: #0000ff;\">Julio 23<br \/><\/span><\/td>\n<td>Firma de compromisos con padres de familia y estudiantes.\u00a0\u00a0\u00a0<\/td>\n<td><\/td>\n<\/tr>\n<tr>\n<td><span style=\"color: #0000ff;\">30 Julio \u00a0\u00a0 3 Agosto<\/span><\/td>\n<td>Aplicaci\u00f3n y recepci\u00f3n de evaluaciones y trabajos.<\/td>\n<td>Docentes, Estudiantes<\/td>\n<\/tr>\n<tr>\n<td><span style=\"color: #0000ff;\">15 Agosto\u00a0<\/span><\/td>\n<td>Publicaci\u00f3n de las notas<\/td>\n<td>Docentes.<\/td>\n<\/tr>\n<tr>\n<td><span style=\"color: #0000ff;\">15 Agosto\u00a0\u00a0\u00a0 19 Agosto<\/span><\/td>\n<td>Subir notas de recuperaci\u00f3n<\/td>\n<td>Docentes.<\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<p> <\/strong><\/em><\/p>\n<p style=\"text-align: justify;\">\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 <\/p>\n<p>6.\u00a0\u00a0\u00a0 CRITERIOS DE EVALUACI\u00d3N.<\/p>\n<p><span style=\"font-size: 10pt; font-family: verdana,geneva;\">Los determinados en el SIE.<\/span><\/p>\n<p><span style=\"font-size: 10pt; font-family: verdana,geneva;\">7.\u00a0\u00a0\u00a0 RECURSOS FISICOS.<\/span><\/p>\n<p><span style=\"font-size: 10pt; font-family: verdana,geneva;\">Fotocopias, textos escolares, Biblioteca, Internet, P\u00e1gina Web.<\/span><\/p>\n<hr \/>\n<p>\u00a0<\/p>\n","protected":false},"excerpt":{"rendered":"<div class=\"mh-excerpt\"><p>PLAN DE MEJORAMIENTO ACADEMICO 2012 \u00a0 Planes de mejoramiento 2011\u00a0 Planes de mejoramiento 2012 \u00a0 1.\u00a0\u00a0\u00a0 OBJETIVOS Aplicar estrategias pedag\u00f3gicas que permitan el mejoramiento acad\u00e9mico\u00a0 <a class=\"mh-excerpt-more\" href=\"https:\/\/aquileoparra.com\/pacho\/2012\/06\/13\/plan-mejoramiento\/\" title=\"PLAN MEJORAMIENTO\">[&#8230;]<\/a><\/p>\n<\/div>","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[14],"tags":[],"class_list":["post-177","post","type-post","status-publish","format-standard","hentry","category-mision"],"_links":{"self":[{"href":"https:\/\/aquileoparra.com\/pacho\/wp-json\/wp\/v2\/posts\/177","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/aquileoparra.com\/pacho\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/aquileoparra.com\/pacho\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/aquileoparra.com\/pacho\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/aquileoparra.com\/pacho\/wp-json\/wp\/v2\/comments?post=177"}],"version-history":[{"count":0,"href":"https:\/\/aquileoparra.com\/pacho\/wp-json\/wp\/v2\/posts\/177\/revisions"}],"wp:attachment":[{"href":"https:\/\/aquileoparra.com\/pacho\/wp-json\/wp\/v2\/media?parent=177"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/aquileoparra.com\/pacho\/wp-json\/wp\/v2\/categories?post=177"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/aquileoparra.com\/pacho\/wp-json\/wp\/v2\/tags?post=177"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}