{"id":3816,"date":"2024-02-05T23:41:50","date_gmt":"2024-02-05T23:41:50","guid":{"rendered":"https:\/\/aquileoparra.com\/pacho\/?p=3816"},"modified":"2024-02-05T23:55:56","modified_gmt":"2024-02-05T23:55:56","slug":"3816","status":"publish","type":"post","link":"https:\/\/aquileoparra.com\/pacho\/2024\/02\/05\/3816\/","title":{"rendered":"\u00a1BIENVENIDOS DOCENTES \u00a1I.E.D. AQUILEO PARRA 2024"},"content":{"rendered":"<div id='gallery-1' class='gallery galleryid-3816 gallery-columns-2 gallery-size-large'><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/aquileoparra.com\/pacho\/2024\/02\/05\/3816\/bienveni-5\/'><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"1024\" src=\"https:\/\/aquileoparra.com\/pacho\/wp-content\/uploads\/2024\/02\/bienveni-5-1024x1024.jpeg\" class=\"attachment-large size-large\" alt=\"\" srcset=\"https:\/\/aquileoparra.com\/pacho\/wp-content\/uploads\/2024\/02\/bienveni-5-1024x1024.jpeg 1024w, https:\/\/aquileoparra.com\/pacho\/wp-content\/uploads\/2024\/02\/bienveni-5-300x300.jpeg 300w, https:\/\/aquileoparra.com\/pacho\/wp-content\/uploads\/2024\/02\/bienveni-5-150x150.jpeg 150w, https:\/\/aquileoparra.com\/pacho\/wp-content\/uploads\/2024\/02\/bienveni-5-768x768.jpeg 768w, https:\/\/aquileoparra.com\/pacho\/wp-content\/uploads\/2024\/02\/bienveni-5.jpeg 1280w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/aquileoparra.com\/pacho\/2024\/02\/05\/3816\/bienveni-2\/'><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"1024\" src=\"https:\/\/aquileoparra.com\/pacho\/wp-content\/uploads\/2024\/02\/bienveni-2-1024x1024.jpeg\" class=\"attachment-large size-large\" alt=\"\" srcset=\"https:\/\/aquileoparra.com\/pacho\/wp-content\/uploads\/2024\/02\/bienveni-2-1024x1024.jpeg 1024w, https:\/\/aquileoparra.com\/pacho\/wp-content\/uploads\/2024\/02\/bienveni-2-300x300.jpeg 300w, https:\/\/aquileoparra.com\/pacho\/wp-content\/uploads\/2024\/02\/bienveni-2-150x150.jpeg 150w, https:\/\/aquileoparra.com\/pacho\/wp-content\/uploads\/2024\/02\/bienveni-2-768x768.jpeg 768w, https:\/\/aquileoparra.com\/pacho\/wp-content\/uploads\/2024\/02\/bienveni-2.jpeg 1280w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/aquileoparra.com\/pacho\/2024\/02\/05\/3816\/mejor-2\/'><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"1024\" src=\"https:\/\/aquileoparra.com\/pacho\/wp-content\/uploads\/2024\/02\/mejor-1-1024x1024.jpeg\" class=\"attachment-large size-large\" alt=\"\" srcset=\"https:\/\/aquileoparra.com\/pacho\/wp-content\/uploads\/2024\/02\/mejor-1-1024x1024.jpeg 1024w, https:\/\/aquileoparra.com\/pacho\/wp-content\/uploads\/2024\/02\/mejor-1-300x300.jpeg 300w, https:\/\/aquileoparra.com\/pacho\/wp-content\/uploads\/2024\/02\/mejor-1-150x150.jpeg 150w, https:\/\/aquileoparra.com\/pacho\/wp-content\/uploads\/2024\/02\/mejor-1-768x768.jpeg 768w, https:\/\/aquileoparra.com\/pacho\/wp-content\/uploads\/2024\/02\/mejor-1.jpeg 1280w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/aquileoparra.com\/pacho\/2024\/02\/05\/3816\/mejor\/'><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"1024\" src=\"https:\/\/aquileoparra.com\/pacho\/wp-content\/uploads\/2024\/02\/mejor-1024x1024.jpeg\" class=\"attachment-large size-large\" alt=\"\" srcset=\"https:\/\/aquileoparra.com\/pacho\/wp-content\/uploads\/2024\/02\/mejor-1024x1024.jpeg 1024w, https:\/\/aquileoparra.com\/pacho\/wp-content\/uploads\/2024\/02\/mejor-300x300.jpeg 300w, https:\/\/aquileoparra.com\/pacho\/wp-content\/uploads\/2024\/02\/mejor-150x150.jpeg 150w, https:\/\/aquileoparra.com\/pacho\/wp-content\/uploads\/2024\/02\/mejor-768x768.jpeg 768w, https:\/\/aquileoparra.com\/pacho\/wp-content\/uploads\/2024\/02\/mejor.jpeg 1280w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/a>\n\t\t\t<\/div><\/figure>\n\t\t<\/div>\n\n<p>\u00a1BIENVENIDOS DOCENTES \u00a1I.E.D. AQUILEO PARRA 2024<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p><em><strong>\u201cCuando eres un educador siempre est\u00e1s en el lugar apropiado a su debido tiempo. No hay horas malas para aprender\u201d.\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 \u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0Betty Anderson<\/strong><\/em><\/p>\n<p>El regreso a las actividades escolares representa para los docentes de esta instituci\u00f3n una nueva oportunidad para crecer en conocimiento, saberes y lo m\u00e1s importante seguir formando ni\u00f1os, j\u00f3venes y adolescentes como verdaderos seres humanos y futuros profesionales. \u00a0El proceso de traslados implementado por la secretaria de Educaci\u00f3n permite que la instituci\u00f3n les abra las puertas a los nuevos docentes brind\u00e1ndoles espacios donde puedan ejercer su trabajo pedag\u00f3gico facilitando, a los estudiantes, los procesos de aprendizaje. Es as\u00ed que la I.E.D Aquileo Parra les da la BIENVENIDA a los docentes de las sedes urbanas y rurales: Lic. Anadehide Silva Sandoval (Clementina Fern\u00e1ndez), Lic. Leidy Katherine Jerez Castillo (Sede Cerro negro) y Lic. Jeimmy Liliana Linares Rodr\u00edguez (sede Capit\u00e1n). Hacen parte de la sede principal los docentes: Lic. Andrea Paola Castrill\u00f3n L\u00f3pez (\u00c9tica y Religi\u00f3n), Lic. Andrea Carolina Qui\u00f1ones Ardila (Humanidades-Lengua extranjera), Lic. Camilo Ignacio Camargo Mar\u00edn (matem\u00e1ticas), Lic. Alba Yaqueline Ariza Fonseca (Humanidades-Lengua extranjera). Lic. Diana Mar\u00eda L\u00f3pez Mu\u00f1oz (ciencias naturales y Ed. Ambiental), Lic. Alexander Garavito Poveda (m\u00fasica). Johanna Castillo (f\u00edsica), Lic. Cesar Ariza (Tecnolog\u00eda e Inform\u00e1tica). De igual manera un agradecimiento especial a los profesores que hicieron parte de la familia aquileista: Lic. Liliana Salamanca (Vda. Cerro Negro) y Lic. Jazm\u00edn Guerrero (Vda. Capit\u00e1n). En la sede principal a los licenciados (as): Edwin, Francisco, Ruggeri, Dora Mercedes y Sandra Patricia. Que la paciencia, la dedicaci\u00f3n y el compromiso a la ense\u00f1anza los acompa\u00f1e en este nuevo caminar que emprenden por la educaci\u00f3n.<\/p>\n","protected":false},"excerpt":{"rendered":"<div class=\"mh-excerpt\"><p>\u00a1BIENVENIDOS DOCENTES \u00a1I.E.D. AQUILEO PARRA 2024 &nbsp; &nbsp; \u201cCuando eres un educador siempre est\u00e1s en el lugar apropiado a su debido tiempo. No hay horas <a class=\"mh-excerpt-more\" href=\"https:\/\/aquileoparra.com\/pacho\/2024\/02\/05\/3816\/\" title=\"\u00a1BIENVENIDOS DOCENTES \u00a1I.E.D. AQUILEO PARRA 2024\">[&#8230;]<\/a><\/p>\n<\/div>","protected":false},"author":1,"featured_media":3819,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-3816","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-uncategorized"],"_links":{"self":[{"href":"https:\/\/aquileoparra.com\/pacho\/wp-json\/wp\/v2\/posts\/3816","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/aquileoparra.com\/pacho\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/aquileoparra.com\/pacho\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/aquileoparra.com\/pacho\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/aquileoparra.com\/pacho\/wp-json\/wp\/v2\/comments?post=3816"}],"version-history":[{"count":4,"href":"https:\/\/aquileoparra.com\/pacho\/wp-json\/wp\/v2\/posts\/3816\/revisions"}],"predecessor-version":[{"id":3824,"href":"https:\/\/aquileoparra.com\/pacho\/wp-json\/wp\/v2\/posts\/3816\/revisions\/3824"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/aquileoparra.com\/pacho\/wp-json\/wp\/v2\/media\/3819"}],"wp:attachment":[{"href":"https:\/\/aquileoparra.com\/pacho\/wp-json\/wp\/v2\/media?parent=3816"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/aquileoparra.com\/pacho\/wp-json\/wp\/v2\/categories?post=3816"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/aquileoparra.com\/pacho\/wp-json\/wp\/v2\/tags?post=3816"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}