{"id":4241,"date":"2025-02-27T00:57:51","date_gmt":"2025-02-27T00:57:51","guid":{"rendered":"https:\/\/aquileoparra.com\/pacho\/?p=4241"},"modified":"2025-02-27T00:59:07","modified_gmt":"2025-02-27T00:59:07","slug":"reconocimiento-a-los-docentes-del-colegio-aquileo-parra","status":"publish","type":"post","link":"https:\/\/aquileoparra.com\/pacho\/2025\/02\/27\/reconocimiento-a-los-docentes-del-colegio-aquileo-parra\/","title":{"rendered":"RECONOCIMIENTO A LOS DOCENTES DEL COLEGIO AQUILEO PARRA"},"content":{"rendered":"<p style=\"text-align: center;\"><strong>RECONOCIMIENTO A LOS DOCENTES DEL COLEGIO AQUILEO PARRA<\/strong><\/p>\n<p style=\"text-align: center;\"><strong><em>Dime y lo olvido, ens\u00e9\u00f1ame y lo recuerdo, invol\u00facrame y lo aprendo.<\/em><\/strong><\/p>\n<p style=\"text-align: center;\"><strong><em>\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 Benjam\u00edn Franklin<\/em><\/strong><\/p>\n<p>&nbsp;<\/p>\n<p>El Colegio Aquileo Parra ha sido testigo de la dedicaci\u00f3n y compromiso de sus docentes a lo largo de los a\u00f1os. Desde sus inicios, la instituci\u00f3n ha contado con educadores comprometidos con la formaci\u00f3n integral de los estudiantes. se ha convertido en un espacio donde los ni\u00f1os, j\u00f3venes y adolescentes no solo adquieren habilidades acad\u00e9micas, sino tambi\u00e9n valores fundamentales como la responsabilidad, la empat\u00eda y el trabajo en equipo.<\/p>\n<p>Los educadores de ayer, con su enfoque tradicional y su esfuerzo por brindar una ense\u00f1anza s\u00f3lida, sentaron las bases de lo que hoy se vive en la instituci\u00f3n: un compromiso por el aprendizaje integral.<\/p>\n<p>Hoy en d\u00eda, los docentes del colegio siguen manteniendo ese mismo esp\u00edritu de dedicaci\u00f3n, pero adapt\u00e1ndose a las nuevas necesidades y desaf\u00edos educativos, incorporando las nuevas tecnolog\u00edas, m\u00e9todos de ense\u00f1anza y un enfoque m\u00e1s humano en el trato con los estudiantes.<\/p>\n<p>Este reconocimiento a los docentes, tanto de ayer como de hoy, es un homenaje a su esfuerzo y pasi\u00f3n por la ense\u00f1anza, que sigue transformando vidas y dejando un legado en la sociedad pachuna.<\/p>\n<hr \/>\n<div id='gallery-1' class='gallery galleryid-4241 gallery-columns-3 gallery-size-large'><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon portrait'>\n\t\t\t\t<a href='https:\/\/aquileoparra.com\/pacho\/2025\/02\/27\/reconocimiento-a-los-docentes-del-colegio-aquileo-parra\/docengt-2\/'><img loading=\"lazy\" decoding=\"async\" width=\"768\" height=\"1024\" src=\"https:\/\/aquileoparra.com\/pacho\/wp-content\/uploads\/2025\/02\/docengt-2-768x1024.jpeg\" class=\"attachment-large size-large\" alt=\"\" srcset=\"https:\/\/aquileoparra.com\/pacho\/wp-content\/uploads\/2025\/02\/docengt-2-768x1024.jpeg 768w, https:\/\/aquileoparra.com\/pacho\/wp-content\/uploads\/2025\/02\/docengt-2-225x300.jpeg 225w, https:\/\/aquileoparra.com\/pacho\/wp-content\/uploads\/2025\/02\/docengt-2.jpeg 960w\" sizes=\"auto, (max-width: 768px) 100vw, 768px\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/aquileoparra.com\/pacho\/2025\/02\/27\/reconocimiento-a-los-docentes-del-colegio-aquileo-parra\/docengt-1\/'><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"768\" src=\"https:\/\/aquileoparra.com\/pacho\/wp-content\/uploads\/2025\/02\/docengt-1-1024x768.jpeg\" class=\"attachment-large size-large\" alt=\"\" srcset=\"https:\/\/aquileoparra.com\/pacho\/wp-content\/uploads\/2025\/02\/docengt-1-1024x768.jpeg 1024w, https:\/\/aquileoparra.com\/pacho\/wp-content\/uploads\/2025\/02\/docengt-1-300x225.jpeg 300w, https:\/\/aquileoparra.com\/pacho\/wp-content\/uploads\/2025\/02\/docengt-1-768x576.jpeg 768w, https:\/\/aquileoparra.com\/pacho\/wp-content\/uploads\/2025\/02\/docengt-1-678x509.jpeg 678w, https:\/\/aquileoparra.com\/pacho\/wp-content\/uploads\/2025\/02\/docengt-1-326x245.jpeg 326w, https:\/\/aquileoparra.com\/pacho\/wp-content\/uploads\/2025\/02\/docengt-1-80x60.jpeg 80w, https:\/\/aquileoparra.com\/pacho\/wp-content\/uploads\/2025\/02\/docengt-1.jpeg 1280w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon portrait'>\n\t\t\t\t<a href='https:\/\/aquileoparra.com\/pacho\/2025\/02\/27\/reconocimiento-a-los-docentes-del-colegio-aquileo-parra\/docengt-3\/'><img loading=\"lazy\" decoding=\"async\" width=\"768\" height=\"1024\" src=\"https:\/\/aquileoparra.com\/pacho\/wp-content\/uploads\/2025\/02\/docengt-3-768x1024.jpeg\" class=\"attachment-large size-large\" alt=\"\" srcset=\"https:\/\/aquileoparra.com\/pacho\/wp-content\/uploads\/2025\/02\/docengt-3-768x1024.jpeg 768w, https:\/\/aquileoparra.com\/pacho\/wp-content\/uploads\/2025\/02\/docengt-3-225x300.jpeg 225w, https:\/\/aquileoparra.com\/pacho\/wp-content\/uploads\/2025\/02\/docengt-3-1152x1536.jpeg 1152w, https:\/\/aquileoparra.com\/pacho\/wp-content\/uploads\/2025\/02\/docengt-3.jpeg 1200w\" sizes=\"auto, (max-width: 768px) 100vw, 768px\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/aquileoparra.com\/pacho\/2025\/02\/27\/reconocimiento-a-los-docentes-del-colegio-aquileo-parra\/docengt-6\/'><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"1024\" src=\"https:\/\/aquileoparra.com\/pacho\/wp-content\/uploads\/2025\/02\/docengt-6-1024x1024.jpeg\" class=\"attachment-large size-large\" alt=\"\" srcset=\"https:\/\/aquileoparra.com\/pacho\/wp-content\/uploads\/2025\/02\/docengt-6-1024x1024.jpeg 1024w, https:\/\/aquileoparra.com\/pacho\/wp-content\/uploads\/2025\/02\/docengt-6-300x300.jpeg 300w, https:\/\/aquileoparra.com\/pacho\/wp-content\/uploads\/2025\/02\/docengt-6-150x150.jpeg 150w, https:\/\/aquileoparra.com\/pacho\/wp-content\/uploads\/2025\/02\/docengt-6-768x768.jpeg 768w, https:\/\/aquileoparra.com\/pacho\/wp-content\/uploads\/2025\/02\/docengt-6.jpeg 1280w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/aquileoparra.com\/pacho\/2025\/02\/27\/reconocimiento-a-los-docentes-del-colegio-aquileo-parra\/docengt-4\/'><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"768\" src=\"https:\/\/aquileoparra.com\/pacho\/wp-content\/uploads\/2025\/02\/docengt-4-1024x768.jpeg\" class=\"attachment-large size-large\" alt=\"\" srcset=\"https:\/\/aquileoparra.com\/pacho\/wp-content\/uploads\/2025\/02\/docengt-4-1024x768.jpeg 1024w, https:\/\/aquileoparra.com\/pacho\/wp-content\/uploads\/2025\/02\/docengt-4-300x225.jpeg 300w, https:\/\/aquileoparra.com\/pacho\/wp-content\/uploads\/2025\/02\/docengt-4-768x576.jpeg 768w, https:\/\/aquileoparra.com\/pacho\/wp-content\/uploads\/2025\/02\/docengt-4-678x509.jpeg 678w, https:\/\/aquileoparra.com\/pacho\/wp-content\/uploads\/2025\/02\/docengt-4-326x245.jpeg 326w, https:\/\/aquileoparra.com\/pacho\/wp-content\/uploads\/2025\/02\/docengt-4-80x60.jpeg 80w, https:\/\/aquileoparra.com\/pacho\/wp-content\/uploads\/2025\/02\/docengt-4.jpeg 1280w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/aquileoparra.com\/pacho\/2025\/02\/27\/reconocimiento-a-los-docentes-del-colegio-aquileo-parra\/docengt-5\/'><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"768\" src=\"https:\/\/aquileoparra.com\/pacho\/wp-content\/uploads\/2025\/02\/docengt-5-1024x768.jpeg\" class=\"attachment-large size-large\" alt=\"\" srcset=\"https:\/\/aquileoparra.com\/pacho\/wp-content\/uploads\/2025\/02\/docengt-5-1024x768.jpeg 1024w, https:\/\/aquileoparra.com\/pacho\/wp-content\/uploads\/2025\/02\/docengt-5-300x225.jpeg 300w, https:\/\/aquileoparra.com\/pacho\/wp-content\/uploads\/2025\/02\/docengt-5-768x576.jpeg 768w, https:\/\/aquileoparra.com\/pacho\/wp-content\/uploads\/2025\/02\/docengt-5-678x509.jpeg 678w, https:\/\/aquileoparra.com\/pacho\/wp-content\/uploads\/2025\/02\/docengt-5-326x245.jpeg 326w, https:\/\/aquileoparra.com\/pacho\/wp-content\/uploads\/2025\/02\/docengt-5-80x60.jpeg 80w, https:\/\/aquileoparra.com\/pacho\/wp-content\/uploads\/2025\/02\/docengt-5.jpeg 1280w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/a>\n\t\t\t<\/div><\/figure>\n\t\t<\/div>\n\n","protected":false},"excerpt":{"rendered":"<div class=\"mh-excerpt\"><p>RECONOCIMIENTO A LOS DOCENTES DEL COLEGIO AQUILEO PARRA Dime y lo olvido, ens\u00e9\u00f1ame y lo recuerdo, invol\u00facrame y lo aprendo. \u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 Benjam\u00edn Franklin &nbsp; El <a class=\"mh-excerpt-more\" href=\"https:\/\/aquileoparra.com\/pacho\/2025\/02\/27\/reconocimiento-a-los-docentes-del-colegio-aquileo-parra\/\" title=\"RECONOCIMIENTO A LOS DOCENTES DEL COLEGIO AQUILEO PARRA\">[&#8230;]<\/a><\/p>\n<\/div>","protected":false},"author":1,"featured_media":4246,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-4241","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-uncategorized"],"_links":{"self":[{"href":"https:\/\/aquileoparra.com\/pacho\/wp-json\/wp\/v2\/posts\/4241","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/aquileoparra.com\/pacho\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/aquileoparra.com\/pacho\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/aquileoparra.com\/pacho\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/aquileoparra.com\/pacho\/wp-json\/wp\/v2\/comments?post=4241"}],"version-history":[{"count":1,"href":"https:\/\/aquileoparra.com\/pacho\/wp-json\/wp\/v2\/posts\/4241\/revisions"}],"predecessor-version":[{"id":4248,"href":"https:\/\/aquileoparra.com\/pacho\/wp-json\/wp\/v2\/posts\/4241\/revisions\/4248"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/aquileoparra.com\/pacho\/wp-json\/wp\/v2\/media\/4246"}],"wp:attachment":[{"href":"https:\/\/aquileoparra.com\/pacho\/wp-json\/wp\/v2\/media?parent=4241"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/aquileoparra.com\/pacho\/wp-json\/wp\/v2\/categories?post=4241"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/aquileoparra.com\/pacho\/wp-json\/wp\/v2\/tags?post=4241"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}