{"id":4341,"date":"2025-07-10T15:22:02","date_gmt":"2025-07-10T15:22:02","guid":{"rendered":"https:\/\/aquileoparra.com\/pacho\/?p=4341"},"modified":"2025-07-21T14:23:48","modified_gmt":"2025-07-21T14:23:48","slug":"4341","status":"publish","type":"post","link":"https:\/\/aquileoparra.com\/pacho\/2025\/07\/10\/4341\/","title":{"rendered":"UNIDOS POR UNA EDUCACI\u00d3N DE CALIDAD: FORO EDUCATIVO INSTITUCIONAL 2025"},"content":{"rendered":"<p style=\"text-align: center;\"><span style=\"color: #0000ff;\"><strong>UNIDOS POR UNA EDUCACI\u00d3N DE CALIDAD: FORO EDUCATIVO INSTITUCIONAL 2025<\/strong><\/span><\/p>\n<p><em><strong>\u201cLa tarea del educador moderno no es talar selvas, sino regar desiertos\u201d<\/strong><\/em><\/p>\n<p><em><strong>\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 C.S. Lewis<\/strong><\/em><\/p>\n<p>Dentro de la Semana Institucional celebrada del 26 al 30 de mayo, se llev\u00f3 a cabo el <strong>Foro Educativo Institucional<\/strong>, un espacio de reflexi\u00f3n, di\u00e1logo y construcci\u00f3n colectiva en torno a los desaf\u00edos y avances del proceso educativo en nuestra instituci\u00f3n. Este foro reuni\u00f3 al delegado de la secretaria de Educaci\u00f3n de Cundinamarca se\u00f1or Carlos Rom\u00e1n, directivos, orientador, docentes y personera estudiantil, quienes se congregaron con el objetivo de visibilizar las estrategias innovadoras que algunos profesores han venido implementando con sus estudiantes, con el fin de fortalecer los procesos de ense\u00f1anza y aprendizaje. Durante el evento se presentaron experiencias pedag\u00f3gicas como:<\/p>\n<table>\n<tbody>\n<tr>\n<td width=\"288\">EXPERIENCIA PEDAGOGICA<\/td>\n<td width=\"288\">INTEGRANTES<\/td>\n<\/tr>\n<tr>\n<td width=\"288\">Viajeros de papel<\/td>\n<td width=\"288\">Licenciados Miriam Rayo, Patricia Ortiz\u00a0\u00a0\u00a0\u00a0 y Dora Ligia Navarrete<\/td>\n<\/tr>\n<tr>\n<td width=\"288\">Pinta cuentos<\/td>\n<td width=\"288\">Licenciados Luz Mary S\u00e1nchez, Katherine Jerez ,Elizabeth palacio, Gerardo Aldana.<\/td>\n<\/tr>\n<tr>\n<td width=\"288\">Mis amigas las Manga<\/td>\n<td width=\"288\">Lic. Andrea Castrill\u00f3n<\/td>\n<\/tr>\n<tr>\n<td width=\"288\">Podcast Historias del campo<\/td>\n<td width=\"288\">Ing. Cesar Ariza<\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<p>Un jurado calificador integrado por: Lic. Elda Lucia Poveda, ing. Juan Pablo Moreno y Lic. Camilo Camargo fue el encargado de valorar cada una de las experiencias presentadas d\u00e1ndole un puntaje mayor al trabajo de la docente ANDREA PAOLA CASTRILL\u00d3N TITULADO \u201cMIS AMIGAS LAS MANGA\u201d un dise\u00f1o de aplicaci\u00f3n (App) orientado a potenciar la inteligencia emocional en los estudiantes. este trabajo fue seleccionado para ser presentado en el FORO EDUCATIVO MUNICIPAL, donde servir\u00e1 como referente de buenas pr\u00e1cticas en el uso de la tecnolog\u00eda para el desarrollo socioemocional.<\/p>\n<p>El foro concluy\u00f3 con un reconocimiento a las experiencias m\u00e1s destacadas, resaltando el compromiso y la dedicaci\u00f3n de los docentes participantes. Este espacio evidenci\u00f3 que la innovaci\u00f3n en el aula es posible cuando se promueve el trabajo colaborativo, la reflexi\u00f3n pedag\u00f3gica y la apertura al cambio.<\/p>\n<div id='gallery-1' class='gallery galleryid-4341 gallery-columns-3 gallery-size-large'><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/aquileoparra.com\/pacho\/2025\/07\/10\/4341\/foro2025-6\/'><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"574\" src=\"https:\/\/aquileoparra.com\/pacho\/wp-content\/uploads\/2025\/07\/FORO2025-6-1024x574.jpeg\" class=\"attachment-large size-large\" alt=\"\" srcset=\"https:\/\/aquileoparra.com\/pacho\/wp-content\/uploads\/2025\/07\/FORO2025-6-1024x574.jpeg 1024w, https:\/\/aquileoparra.com\/pacho\/wp-content\/uploads\/2025\/07\/FORO2025-6-300x168.jpeg 300w, https:\/\/aquileoparra.com\/pacho\/wp-content\/uploads\/2025\/07\/FORO2025-6-768x431.jpeg 768w, https:\/\/aquileoparra.com\/pacho\/wp-content\/uploads\/2025\/07\/FORO2025-6-1536x861.jpeg 1536w, https:\/\/aquileoparra.com\/pacho\/wp-content\/uploads\/2025\/07\/FORO2025-6-678x381.jpeg 678w, https:\/\/aquileoparra.com\/pacho\/wp-content\/uploads\/2025\/07\/FORO2025-6.jpeg 1600w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon portrait'>\n\t\t\t\t<a href='https:\/\/aquileoparra.com\/pacho\/2025\/07\/10\/4341\/foro2025-1\/'><img loading=\"lazy\" decoding=\"async\" width=\"574\" height=\"1024\" src=\"https:\/\/aquileoparra.com\/pacho\/wp-content\/uploads\/2025\/07\/FORO2025-1-574x1024.jpeg\" class=\"attachment-large size-large\" alt=\"\" srcset=\"https:\/\/aquileoparra.com\/pacho\/wp-content\/uploads\/2025\/07\/FORO2025-1-574x1024.jpeg 574w, https:\/\/aquileoparra.com\/pacho\/wp-content\/uploads\/2025\/07\/FORO2025-1-168x300.jpeg 168w, https:\/\/aquileoparra.com\/pacho\/wp-content\/uploads\/2025\/07\/FORO2025-1-768x1370.jpeg 768w, https:\/\/aquileoparra.com\/pacho\/wp-content\/uploads\/2025\/07\/FORO2025-1-861x1536.jpeg 861w, https:\/\/aquileoparra.com\/pacho\/wp-content\/uploads\/2025\/07\/FORO2025-1.jpeg 897w\" sizes=\"auto, (max-width: 574px) 100vw, 574px\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/aquileoparra.com\/pacho\/2025\/07\/10\/4341\/foro2025-5\/'><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"574\" src=\"https:\/\/aquileoparra.com\/pacho\/wp-content\/uploads\/2025\/07\/FORO2025-5-1024x574.jpeg\" class=\"attachment-large size-large\" alt=\"\" srcset=\"https:\/\/aquileoparra.com\/pacho\/wp-content\/uploads\/2025\/07\/FORO2025-5-1024x574.jpeg 1024w, https:\/\/aquileoparra.com\/pacho\/wp-content\/uploads\/2025\/07\/FORO2025-5-300x168.jpeg 300w, https:\/\/aquileoparra.com\/pacho\/wp-content\/uploads\/2025\/07\/FORO2025-5-768x431.jpeg 768w, https:\/\/aquileoparra.com\/pacho\/wp-content\/uploads\/2025\/07\/FORO2025-5-1536x861.jpeg 1536w, https:\/\/aquileoparra.com\/pacho\/wp-content\/uploads\/2025\/07\/FORO2025-5-678x381.jpeg 678w, https:\/\/aquileoparra.com\/pacho\/wp-content\/uploads\/2025\/07\/FORO2025-5.jpeg 1600w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/aquileoparra.com\/pacho\/2025\/07\/10\/4341\/foro2025-4\/'><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"574\" src=\"https:\/\/aquileoparra.com\/pacho\/wp-content\/uploads\/2025\/07\/FORO2025-4-1024x574.jpeg\" class=\"attachment-large size-large\" alt=\"\" srcset=\"https:\/\/aquileoparra.com\/pacho\/wp-content\/uploads\/2025\/07\/FORO2025-4-1024x574.jpeg 1024w, https:\/\/aquileoparra.com\/pacho\/wp-content\/uploads\/2025\/07\/FORO2025-4-300x168.jpeg 300w, https:\/\/aquileoparra.com\/pacho\/wp-content\/uploads\/2025\/07\/FORO2025-4-768x431.jpeg 768w, https:\/\/aquileoparra.com\/pacho\/wp-content\/uploads\/2025\/07\/FORO2025-4-1536x861.jpeg 1536w, https:\/\/aquileoparra.com\/pacho\/wp-content\/uploads\/2025\/07\/FORO2025-4-678x381.jpeg 678w, https:\/\/aquileoparra.com\/pacho\/wp-content\/uploads\/2025\/07\/FORO2025-4.jpeg 1600w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/aquileoparra.com\/pacho\/2025\/07\/10\/4341\/foro2025-3\/'><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"574\" src=\"https:\/\/aquileoparra.com\/pacho\/wp-content\/uploads\/2025\/07\/FORO2025-3-1024x574.jpeg\" class=\"attachment-large size-large\" alt=\"\" srcset=\"https:\/\/aquileoparra.com\/pacho\/wp-content\/uploads\/2025\/07\/FORO2025-3-1024x574.jpeg 1024w, https:\/\/aquileoparra.com\/pacho\/wp-content\/uploads\/2025\/07\/FORO2025-3-300x168.jpeg 300w, https:\/\/aquileoparra.com\/pacho\/wp-content\/uploads\/2025\/07\/FORO2025-3-768x431.jpeg 768w, https:\/\/aquileoparra.com\/pacho\/wp-content\/uploads\/2025\/07\/FORO2025-3-1536x861.jpeg 1536w, https:\/\/aquileoparra.com\/pacho\/wp-content\/uploads\/2025\/07\/FORO2025-3-678x381.jpeg 678w, https:\/\/aquileoparra.com\/pacho\/wp-content\/uploads\/2025\/07\/FORO2025-3.jpeg 1600w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/aquileoparra.com\/pacho\/2025\/07\/10\/4341\/foro2025-2\/'><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"574\" src=\"https:\/\/aquileoparra.com\/pacho\/wp-content\/uploads\/2025\/07\/FORO2025-2-1024x574.jpeg\" class=\"attachment-large size-large\" alt=\"\" srcset=\"https:\/\/aquileoparra.com\/pacho\/wp-content\/uploads\/2025\/07\/FORO2025-2-1024x574.jpeg 1024w, https:\/\/aquileoparra.com\/pacho\/wp-content\/uploads\/2025\/07\/FORO2025-2-300x168.jpeg 300w, https:\/\/aquileoparra.com\/pacho\/wp-content\/uploads\/2025\/07\/FORO2025-2-768x431.jpeg 768w, https:\/\/aquileoparra.com\/pacho\/wp-content\/uploads\/2025\/07\/FORO2025-2-1536x861.jpeg 1536w, https:\/\/aquileoparra.com\/pacho\/wp-content\/uploads\/2025\/07\/FORO2025-2-678x381.jpeg 678w, https:\/\/aquileoparra.com\/pacho\/wp-content\/uploads\/2025\/07\/FORO2025-2.jpeg 1600w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/a>\n\t\t\t<\/div><\/figure>\n\t\t<\/div>\n\n","protected":false},"excerpt":{"rendered":"<div class=\"mh-excerpt\"><p>UNIDOS POR UNA EDUCACI\u00d3N DE CALIDAD: FORO EDUCATIVO INSTITUCIONAL 2025 \u201cLa tarea del educador moderno no es talar selvas, sino regar desiertos\u201d \u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 C.S. Lewis <a class=\"mh-excerpt-more\" href=\"https:\/\/aquileoparra.com\/pacho\/2025\/07\/10\/4341\/\" title=\"UNIDOS POR UNA EDUCACI\u00d3N DE CALIDAD: FORO EDUCATIVO INSTITUCIONAL 2025\">[&#8230;]<\/a><\/p>\n<\/div>","protected":false},"author":1,"featured_media":4346,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-4341","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-uncategorized"],"_links":{"self":[{"href":"https:\/\/aquileoparra.com\/pacho\/wp-json\/wp\/v2\/posts\/4341","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/aquileoparra.com\/pacho\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/aquileoparra.com\/pacho\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/aquileoparra.com\/pacho\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/aquileoparra.com\/pacho\/wp-json\/wp\/v2\/comments?post=4341"}],"version-history":[{"count":3,"href":"https:\/\/aquileoparra.com\/pacho\/wp-json\/wp\/v2\/posts\/4341\/revisions"}],"predecessor-version":[{"id":4385,"href":"https:\/\/aquileoparra.com\/pacho\/wp-json\/wp\/v2\/posts\/4341\/revisions\/4385"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/aquileoparra.com\/pacho\/wp-json\/wp\/v2\/media\/4346"}],"wp:attachment":[{"href":"https:\/\/aquileoparra.com\/pacho\/wp-json\/wp\/v2\/media?parent=4341"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/aquileoparra.com\/pacho\/wp-json\/wp\/v2\/categories?post=4341"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/aquileoparra.com\/pacho\/wp-json\/wp\/v2\/tags?post=4341"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}